{"id":2120,"date":"2022-08-22T16:54:07","date_gmt":"2022-08-22T16:54:07","guid":{"rendered":"https:\/\/francescoangelico.com\/event\/siegfried-2\/"},"modified":"2022-08-22T16:55:22","modified_gmt":"2022-08-22T16:55:22","slug":"siegfried-2","status":"publish","type":"tribe_events","link":"https:\/\/francescoangelico.com\/it\/event\/siegfried-2\/","title":{"rendered":"Siegfried"},"content":{"rendered":"<p>Richard Wagner<\/p>\n<p>Staatstheater Kassel<\/p>\n<p>Stage Director: Markus Dietz<\/p>\n","protected":false},"excerpt":{"rendered":"Richard Wagner Staatstheater Kassel Stage Director: Markus Dietz","protected":false},"author":3,"featured_media":0,"template":"","meta":{"_acf_changed":false,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-2120","tribe_events","type-tribe_events","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/francescoangelico.com\/it\/wp-json\/wp\/v2\/tribe_events\/2120","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/francescoangelico.com\/it\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/francescoangelico.com\/it\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/francescoangelico.com\/it\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":1,"href":"https:\/\/francescoangelico.com\/it\/wp-json\/wp\/v2\/tribe_events\/2120\/revisions"}],"predecessor-version":[{"id":2123,"href":"https:\/\/francescoangelico.com\/it\/wp-json\/wp\/v2\/tribe_events\/2120\/revisions\/2123"}],"wp:attachment":[{"href":"https:\/\/francescoangelico.com\/it\/wp-json\/wp\/v2\/media?parent=2120"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/francescoangelico.com\/it\/wp-json\/wp\/v2\/tags?post=2120"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/francescoangelico.com\/it\/wp-json\/wp\/v2\/tribe_events_cat?post=2120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}